{"id":59039,"date":"2024-07-28T23:36:37","date_gmt":"2024-07-28T23:36:37","guid":{"rendered":"https:\/\/www.transfergo.com\/?p=59039"},"modified":"2025-01-08T16:46:16","modified_gmt":"2025-01-08T16:46:16","slug":"apl-etudiants-etrangers","status":"publish","type":"post","link":"https:\/\/www.transfergo.com\/fr\/apl-etudiants-etrangers","title":{"rendered":"APL \u00e9tudiants \u00e9trangers : un guide complet pour en b\u00e9n\u00e9ficier et en faire la demande"},"content":{"rendered":"\n<p>L\u2019Aide Personnalis\u00e9e pour le Logement, APL \u00e9tudiants \u00e9trangers en France : en avez-vous entendu parler ?<\/p>\n\n\n\n<p>L\u2019une des difficult\u00e9s majeures que rencontrent les <a href=\"https:\/\/www.transfergo.com\/fr\/parcours-etudiant-etranger-en-france\">\u00e9tudiants \u00e9trangers<\/a> sur le sol fran\u00e7ais est celle du logement. Comment trouver un endroit d\u00e9cent dans la limite des moyens financiers disponibles. Il est encore plus malais\u00e9 de s\u00e9curiser un local dans les grandes villes et cit\u00e9s universitaires si vous venez d\u2019un milieu modeste. Et quand bien m\u00eame l\u2019\u00e9tudiant \u00e9tranger r\u00e9ussit \u00e0 trouver ladite habitation, il doit encore s\u2019assurer de pouvoir payer son loyer dans les d\u00e9lais pour rester cr\u00e9dible et poursuivre ses \u00e9tudes sans souci d\u2019h\u00e9bergement.<\/p>\n\n\n\n<p>Consciente des difficult\u00e9s locatives auxquelles doivent faire face les foyers modestes, la Caf (Caisse d&#8217;Allocations familiales) octroie diverses aides au logement. Parmi elles, l\u2019APL permet aux \u00e9tudiants \u00e9trangers \u00e9ligibles de recevoir une aide financi\u00e8re visant sp\u00e9cifiquement \u00e0 all\u00e9ger la charge locative. Mais quelles sont ces conditions ? Comment demander une APL et quelles sont les pi\u00e8ces \u00e0 fournir ?&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"683\" width=\"1024\" src=\"https:\/\/www.transfergo.com\/fr\/wp-content\/uploads\/2024\/08\/iStock-1467685601-1024x683.jpg\" alt=\"apl \u00e9tudiants \u00e9trangers\" class=\"wp-image-75240\"\/><\/figure>\n\n\n\n<div class=\"wp-block-rank-math-toc-block\" id=\"rank-math-toc\"><h2>Contenu:<\/h2><nav><ul><li class=\"\"><a href=\"#apl-etudiants-etrangers-et-autres-aides-au-logement-de-la-caf\">APL \u00e9tudiants \u00e9trangers et autres aides au logement de la Caf<\/a><\/li><li class=\"\"><a href=\"#quelles-sont-les-conditions-deligibilite-de-l-apl-etudiants-etrangers\">Quelles sont les conditions d\u2019\u00e9ligibilit\u00e9 de l\u2019APL \u00e9tudiants \u00e9trangers ?<\/a><ul><li class=\"\"><a href=\"#eligibilite-du-logement-pour-l-apl\">\u00c9ligibilit\u00e9 du logement pour l\u2019APL<\/a><\/li><li class=\"\"><a href=\"#eligibilite-de-letudiant-etranger-pour-l-apl\">\u00c9ligibilit\u00e9 de l\u2019\u00e9tudiant \u00e9tranger pour l\u2019APL<\/a><\/li><\/ul><\/li><li class=\"\"><a href=\"#quelles-sont-les-pieces-a-fournir\">Quelles sont les pi\u00e8ces \u00e0 fournir ?\u00a0<\/a><\/li><li class=\"\"><a href=\"#comment-beneficier-dune-apl-en-tant-quetudiant-etranger\">Comment b\u00e9n\u00e9ficier d\u2019une APL en tant qu\u2019\u00e9tudiant \u00e9tranger ?<\/a><\/li><li class=\"\"><a href=\"#a-combien-seleve-l-apl-etudiants-etrangers\">\u00c0 combien s\u2019\u00e9l\u00e8ve l&#8217;APL \u00e9tudiants \u00e9trangers ?<\/a><\/li><li class=\"\"><a href=\"#existe-t-il-une-apl-pour-proprietaire\">Existe-t-il une APL pour propri\u00e9taire ?<\/a><\/li><li class=\"\"><a href=\"#creer-un-compte-transfer-go-pour-votre-apl\">Cr\u00e9er un compte TransferGo pour votre APL<\/a><\/li><\/ul><\/nav><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"apl-etudiants-etrangers-et-autres-aides-au-logement-de-la-caf\">APL \u00e9tudiants \u00e9trangers et autres aides au logement de la Caf<\/h2>\n\n\n\n<p>La Caisse d&#8217;Allocations familiales ou CAF est un organisme de droit priv\u00e9 qui verse des aides aux personnes et foyers en difficult\u00e9. Ces aides peuvent \u00eatre d\u2019ordre professionnel (RSA, Prime d\u2019activit\u00e9) ou familiale (Allocations familiales, allocation de rentr\u00e9e, compl\u00e9ment de libre choix du mode de garde, allocation de soutien familial, etc.). La Caf verse aussi des aides au logement.<\/p>\n\n\n\n<p>L\u2019<a href=\"https:\/\/www.service-public.fr\/particuliers\/vosdroits\/F12006\" target=\"_blank\" rel=\"noopener\">allocation personnalis\u00e9e au logement APL<\/a> ne s\u2019adresse pas sp\u00e9cifiquement aux \u00e9trangers. Elle concerne toute personne r\u00e9sidant sur le territoire fran\u00e7ais, disposant d\u2019un revenu modeste et r\u00e9pondant \u00e0 des conditions d\u2019\u00e9ligibilit\u00e9 sp\u00e9cifiques. Cette large plage de s\u00e9lection permet aussi bien aux \u00e9tudiants \u00e9trangers qu\u2019aux Fran\u00e7ais de b\u00e9n\u00e9ficier de l\u2019APL apr\u00e8s en avoir fait la demande.<\/p>\n\n\n\n<p>Les personnes non \u00e9ligibles pour l\u2019APL, peuvent demander une ALF (allocation de logement familial) ou une ALS (Allocation de logement social).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"quelles-sont-les-conditions-deligibilite-de-l-apl-etudiants-etrangers\">Quelles sont les conditions d\u2019\u00e9ligibilit\u00e9 de l\u2019APL \u00e9tudiants \u00e9trangers ?<\/h2>\n\n\n\n<p>En tant qu\u2019\u00e9tudiant \u00e9tranger, il faut savoir que les conditions d\u2019\u00e9ligibilit\u00e9 prennent compte du logement et du locataire. Nous sommes bien loin de la proc\u00e9dure simplifi\u00e9e pour <a href=\"https:\/\/www.transfergo.com\/fr\/\">cr\u00e9er un compte sur TransferGo<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"eligibilite-du-logement-pour-l-apl\">\u00c9ligibilit\u00e9 du logement pour l\u2019APL<\/h3>\n\n\n\n<p>L\u2019APL \u00e9tudiants \u00e9trangers ne peut \u00eatre accord\u00e9e que pour les logements conventionn\u00e9s. Ceci suppose que le propri\u00e9taire a sign\u00e9 une convention avec l&#8217;\u00c9tat stipulant qu\u2019il s\u2019engage \u00e0 respecter un plafond locatif estim\u00e9 par les intuitions ad hoc. Vous devez donc v\u00e9rifier ce crit\u00e8re avant de louer un local, que vous soyez en France ou \u00e0 l\u2019\u00e9tranger. Il suffit de vous renseigner aupr\u00e8s de votre propri\u00e9taire. En cas de sous-location, la sous-location doit \u00eatre d\u00fbment signal\u00e9e et agr\u00e9\u00e9e du propri\u00e9taire afin de pr\u00e9tendre \u00e0 une aide au logement de la Caf. APL  \u00e9tudiants \u00e9trangers est aussi accord\u00e9e pour les logements sociaux et universitaires.<\/p>\n\n\n\n<p>Le logement de l\u2019\u00e9tudiant \u00e9tranger doit \u00eatre d\u00e9cent pour garantir l\u2019attribution d\u2019une APL. Outre les infrastructures de base, le logement doit couvrir au moins 9 m<sup>2<\/sup> pour un \u00e9tudiant \u00e9tranger vivant seul et 16 m<sup>2<\/sup> pour deux. Pour chaque personne additionnelle, il devra garantir une surface suppl\u00e9mentaire de 9 m<sup>2<\/sup>. Enfin, pour ce qui est du logement de l\u2019\u00e9tudiant \u00e9tranger visant une allocation, l\u2019APL ne prend en compte que la r\u00e9sidence principale. L\u2019\u00e9tudiant \u00e9tranger ou fran\u00e7ais ne peut donc b\u00e9n\u00e9ficier que d\u2019une seule APL par personne.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"eligibilite-de-letudiant-etranger-pour-l-apl\">\u00c9ligibilit\u00e9 de l\u2019\u00e9tudiant \u00e9tranger pour l\u2019APL<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"683\" width=\"1024\" src=\"https:\/\/www.transfergo.com\/fr\/wp-content\/uploads\/2024\/08\/iStock-1474998532-1024x683.jpg\" alt=\"apl \u00e9tudiants \u00e9trangers 1\" class=\"wp-image-75252\"\/><\/figure>\n\n\n\n<p>Comme annonc\u00e9 plus haut, APL \u00e9tudiants \u00e9trangers, est accord\u00e9 aux personnes dont les revenus sont modestes. Ceci suppose que vos revenus ou sources de revenus ne vous permettent pas de d\u00e9passer le plafond annuel fix\u00e9 en fonction de votre situation familiale. Le revenu et les ressources prennent en compte vos entr\u00e9es personnelles d\u2019argent et les revenus des parents si l\u2019\u00e9tudiant \u00e9tranger est toujours sous tutelle parentale.<\/p>\n\n\n\n<p>Outre le point des revenus, <a href=\"https:\/\/www.croos.fr\/blog\/etudiants-etrangers-comment-demander-l-aide-financiere-au-logement-de-la-caf\" target=\"_blank\" rel=\"noopener\">si vous \u00eates un \u00e9tudiant \u00e9tranger<\/a>, vous devez r\u00e9unir les conditions ci-dessous pour maximiser les chances d\u2019octroi d\u2019une allocation personnalis\u00e9e pour le logement :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Avoir un permis ou titre de s\u00e9jour toujours valide ;<\/li>\n\n\n\n<li>R\u00e9sider en France de mani\u00e8re r\u00e9guli\u00e8re et stable ;<\/li>\n\n\n\n<li>Justifier d\u2019une r\u00e9sidence d\u2019au moins 08 mois dans le logement requis au cours des douze mois successifs et pr\u00e9c\u00e9dant la demande APL \u00e9tudiants \u00e9trangers;<\/li>\n\n\n\n<li>Avoir un contrat d\u00fbment sign\u00e9 pour un logement conventionn\u00e9 ; ledit contrat doit porter le nom de l\u2019\u00e9tudiant \u00e9tranger ; si vous \u00eates en colocation, votre colocataire doit d\u00e9poser la demande d\u2019APL en m\u00eame temps que vous. Si vous \u00eates en couple, l\u2019attribution de l\u2019APL est unique pour les deux partenaires ;<\/li>\n\n\n\n<li>Disposer d\u2019un compte en banque dans une institution du territoire fran\u00e7ais ;<\/li>\n\n\n\n<li>N\u2019avoir aucun lien de parent\u00e9 avec le propri\u00e9taire de la maison ;<\/li>\n\n\n\n<li>Ne pas b\u00e9n\u00e9ficier d\u2019une autre allocation d\u2019\u00c9tat ;<\/li>\n\n\n\n<li>Ne pas \u00eatre rattach\u00e9 \u00e0 un autre foyer fiscal soumis \u00e0 l\u2019imp\u00f4t sur la fortune immobili\u00e8re.<\/li>\n<\/ul>\n\n\n\n<p>Si vous \u00eates un \u00e9tudiant \u00e9tranger et que vos parents vivent en France, l\u2019attribution d\u2019une APL \u00e9tudiants \u00e9trangers peut entra\u00eener une diminution ou la suspension des allocations familiales de votre famille. Par ailleurs, les conditions de vie d\u2019un \u00e9tudiant \u00e9tranger pouvant \u00eatre dynamiques, la Caf r\u00e9vise r\u00e9guli\u00e8rement l\u2019\u00e9ligibilit\u00e9 de ses b\u00e9n\u00e9ficiaires. Enfin, si vous disposez ou b\u00e9n\u00e9ficiez d\u2019un patrimoine h\u00e9r\u00e9ditaire, celui-ci est int\u00e9gr\u00e9 dans le calcul de l\u2019APL.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"quelles-sont-les-pieces-a-fournir\">Quelles sont les pi\u00e8ces \u00e0 fournir ?&nbsp;<\/h2>\n\n\n\n<p>\u00c0 l\u2019instar de leurs condisciples fran\u00e7ais, les \u00e9tudiants \u00e9trangers doivent fournir des informations et des documents sp\u00e9cifiques. Il faut :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Avoir un compte valide dans une banque en France et fournira son RIB au cours de la demande d\u2019APL \u00e9tudiants \u00e9trangers ; si vous ou vos parents \u00eates allocataire, il faudra fournir un num\u00e9ro d\u2019allocataire ;<\/li>\n\n\n\n<li>Fournir une copie de votre contrat de location sign\u00e9 par le propri\u00e9taire et pr\u00e9cisant les caract\u00e9ristiques du logement (superficie, loyer, ameublement, colocataires, etc.) ; si le bailleur est une agence ou une entit\u00e9 morale, il faudra aussi renseigner le num\u00e9ro de SIRET ;<\/li>\n\n\n\n<li>Fournir une preuve de revenus des habitants du foyer au cours des 12 mois derniers ;<\/li>\n\n\n\n<li>Fournir les preuves de votre identit\u00e9 et une copie certifi\u00e9e de votre acte de naissance traduit en fran\u00e7ais ;<\/li>\n\n\n\n<li>Donner une preuve de l\u2019inscription au RSSE (R\u00e9gime de S\u00e9curit\u00e9 sociale \u00e9tudiante) ;<\/li>\n\n\n\n<li>Si vous \u00eates ressortissant de la zone UE, vous aurez besoin de votre formulaire (ou autre preuve) d\u2019inscription et d\u2019une copie de votre carte europ\u00e9enne d\u2019assurance maladie ;<\/li>\n\n\n\n<li>Si vous \u00eates ressortissant d\u2019une zone hors UE, vous aurez besoin d\u2019un titre de s\u00e9jour en cours de validit\u00e9.&nbsp;<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"comment-beneficier-dune-apl-en-tant-quetudiant-etranger\">Comment b\u00e9n\u00e9ficier d\u2019une APL en tant qu\u2019\u00e9tudiant \u00e9tranger ?<\/h2>\n\n\n\n<p>Pour b\u00e9n\u00e9ficier d\u2019une aide personnalis\u00e9e au logement, vous pouvez faire la demande int\u00e9gralement en ligne sur le site de la Caf. Si vous vivez d\u00e9j\u00e0 sur le territoire fran\u00e7ais, vous pouvez aussi vous rendre \u00e0 l\u2019agence d\u00e9partementale de la Caf pour profiter d\u2019une assistance \u00e0 l\u2019inscription. Les personnes d\u00e9pendant du r\u00e9gime agricole peuvent passer par la MSA pour obtenir une APL \u00e9tudiants \u00e9trangers.<\/p>\n\n\n\n<p>La majorit\u00e9 des \u00e9tudiants \u00e9trangers ne sont pas des allocataires de la Caf. Il faudra donc cr\u00e9er un compte en tant que non-allocataire. Vous recevrez ensuite un code confidentiel qui vous donnera acc\u00e8s \u00e0 votre compte. Il suffit ensuite d\u2019acc\u00e9der \u00e0 la rubrique \u00ab demande de prestation \u00bb et de faire la demande d\u2019APL \u00e9tudiants \u00e9trangers d\u00e8s que vous emm\u00e9nagez dans votre local conventionn\u00e9.<\/p>\n\n\n\n<p>Si vous \u00eates un \u00e9tudiant \u00e9tranger allocataire en France, et que vous d\u00e9m\u00e9nagez dans un logement conventionn\u00e9, il faudra faire votre demande en tant qu\u2019allocataire. Ici, vous devez mettre \u00e0 jour vos donn\u00e9es pour interrompre les allocations en cours et faire la demande pour une nouvelle APL.<\/p>\n\n\n\n<p>Si vous \u00eates en colocation, chaque colocataire devra faire sa demande pour respecter les crit\u00e8res d\u2019\u00e9ligibilit\u00e9 \u00e0 l\u2019aide logement CAF. Notez que l\u2019octroi de l\u2019aide au logement n\u2019est pas r\u00e9troactif. Votre demande d\u2019APL doit donc \u00eatre faite d\u00e8s que vous signez le contrat de bail pour en b\u00e9n\u00e9ficier le plus t\u00f4t possible.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"a-combien-seleve-l-apl-etudiants-etrangers\">\u00c0 combien s\u2019\u00e9l\u00e8ve l&#8217;APL \u00e9tudiants \u00e9trangers ?<\/h2>\n\n\n\n<p>L\u2019APL \u00e9tudiants \u00e9trangers est calcul\u00e9e en fonction de plusieurs param\u00e8tres : le montant du loyer, la localisation du logement, vos revenus, le nombre de personnes \u00e0 charge ou de colocataires, etc. La valeur de l\u2019allocation peut donc varier d\u2019un \u00e9tudiant \u00e0 un autre. Pour avoir une estimation du montant de votre APL, vous pouvez utiliser le simulateur de l\u2019aide au logement disponible sur le site de la Caf. Notons que la valeur r\u00e9elle de l\u2019APL peut varier en fonction des param\u00e8tres non inclus dans la simulation et du flux r\u00e9el du secteur immobilier. Enfin, l\u2019outil indique \u00e0 l\u2019\u00e9tudiant s\u2019il remplit les conditions pour \u00eatre \u00e9ligible \u00e0 l\u2019APL ou \u00e0 d\u2019autres aides au logement.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"683\" width=\"1024\" src=\"https:\/\/www.transfergo.com\/fr\/wp-content\/uploads\/2024\/08\/iStock-1464245432-1024x683.jpg\" alt=\"apl \u00e9tudiants \u00e9trangers 2\" class=\"wp-image-75263\"\/><\/figure>\n\n\n\n<p>Dans l\u2019\u00e9ventualit\u00e9 o\u00f9 votre APL ne suffit pas \u00e0 supporter la charge de votre loyer, vous pouvez vous faire aider de vos proches \u00e0 l\u2019\u00e9tranger. Encouragez-les \u00e0 cr\u00e9er un compte et \u00e0 profiter du <a href=\"https:\/\/www.transfergo.com\/fr\/parrainez-un-ami\">parrainage TransferGo<\/a> pour vous envoyer des transferts internationaux sans frais.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"existe-t-il-une-apl-pour-proprietaire\">Existe-t-il une APL pour propri\u00e9taire ?<\/h2>\n\n\n\n<p>Vous l\u2019aurez compris, le r\u00f4le du propri\u00e9taire est essentiel en amont pour l\u2019obtention d\u2019une APL pour les \u00e9tudiants \u00e9trangers. Toutefois, en 2025, les propri\u00e9taires ne peuvent pas b\u00e9n\u00e9ficier d\u2019une aide personnalis\u00e9e au logement. L\u2019APL accession a \u00e9t\u00e9 supprim\u00e9e en 2018 pour les logements neufs et d\u00e8s 2020 pour les anciens logements.<\/p>\n\n\n\n<p>2020 marque donc la fin de l\u2019APL accession. Les propri\u00e9taires peuvent n\u00e9anmoins profiter d\u2019autres aides au logement : le fonds de solidarit\u00e9 logement (FSL), l\u2019aide au propri\u00e9taire de l\u2019Anah, le pr\u00eat propri\u00e9taire en difficult\u00e9 de la Caf, les aides de l\u2019ADIL, de l\u2019assistance sociale, du centre des imp\u00f4ts, etc.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"creer-un-compte-transfer-go-pour-votre-apl\">Cr\u00e9er un compte TransferGo pour votre APL<\/h2>\n\n\n\n<p>Pour b\u00e9n\u00e9ficier d\u2019une APL \u00e9tudiants \u00e9trangers, vous devez avoir un titre de s\u00e9jour, cr\u00e9er un compte bancaire et s\u00e9curiser un bail pour votre logement. Ceci suppose de disposer d\u2019un moyen rapide et s\u00fbr pour vos transactions bancaires. TransferGo offre aux \u00e9tudiants \u00e9trangers une solution ergonomique pour envoyer (ou recevoir) de l\u2019argent depuis leur pays d\u2019origine.<\/p>\n\n\n\n<p>Disponible sur t\u00e9l\u00e9phone ou tablette, TransferGo autorise les r\u00e9sidents de plus de 60 pays r\u00e9partis dans tous les continents, \u00e0 ouvrir un compte bancaire. Vous pouvez ainsi d\u00e9tenir un compte qui sera domicili\u00e9 en France tout en facilitant le transfert de devises. Enfin, le compte bancaire TransferGo peut \u00eatre cr\u00e9\u00e9 en quelques heures. En somme, elle vous permet de souscrire plus vite \u00e0 l\u2019APL et de recevoir le montant de l\u2019aide.&nbsp;<\/p>\n\n\n\n<p><a href=\"https:\/\/app.transfergo.com\/fr\/user\/welcome\" target=\"_blank\" rel=\"noopener\">Cr\u00e9ez votre compte TransferGo<\/a> d\u00e8s maintenant et profitez de conditions simplifi\u00e9es pour envoyer et recevoir de l\u2019argent. Tirez profit de cet influx additionnel et de votre APL pour payer votre loyer en temps et en heure, sans handicaper vos finances.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Aide Personnalis\u00e9e pour le Logement, APL \u00e9tudiants \u00e9trangers en France : en avez-vous entendu parler ? L\u2019une des difficult\u00e9s majeures que rencontrent les \u00e9tudiants \u00e9trangers sur le sol fran\u00e7ais est celle du logement. Comment trouver un endroit d\u00e9cent dans la limite des moyens financiers disponibles. Il est encore plus malais\u00e9 de s\u00e9curiser un local dans [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":75252,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1342,1340],"tags":[],"business_case_studies_tags":[],"class_list":["post-59039","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-etudier-a-letranger","category-vivre-a-letranger"],"parsely":{"version":"1.1.0","canonical_url":"https:\/\/transfergo.com\/fr\/apl-etudiants-etrangers","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"APL \u00e9tudiants \u00e9trangers : un guide complet pour en b\u00e9n\u00e9ficier et en faire la demande","url":"http:\/\/www.transfergo.com\/fr\/apl-etudiants-etrangers","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/www.transfergo.com\/fr\/apl-etudiants-etrangers"},"thumbnailUrl":"https:\/\/www.transfergo.com\/wp-content\/uploads\/2024\/08\/iStock-1474998532.jpg?resize=150,150","image":{"@type":"ImageObject","url":"https:\/\/www.transfergo.com\/wp-content\/uploads\/2024\/08\/iStock-1474998532.jpg"},"articleSection":"\u00c9tudier \u00e0 l'\u00e9tranger","author":[{"@type":"Person","name":"TransferGo Team"}],"creator":["TransferGo Team"],"publisher":{"@type":"Organization","name":"TransferGo","logo":""},"keywords":[],"dateCreated":"2024-07-28T23:36:37Z","datePublished":"2024-07-28T23:36:37Z","dateModified":"2025-01-08T16:46:16Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"APL \\u00e9tudiants \\u00e9trangers : un guide complet pour en b\\u00e9n\\u00e9ficier et en faire la demande\",\"url\":\"http:\\\/\\\/www.transfergo.com\\\/fr\\\/apl-etudiants-etrangers\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.transfergo.com\\\/fr\\\/apl-etudiants-etrangers\"},\"thumbnailUrl\":\"https:\\\/\\\/www.transfergo.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/iStock-1474998532.jpg?resize=150,150\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.transfergo.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/iStock-1474998532.jpg\"},\"articleSection\":\"\\u00c9tudier \\u00e0 l'\\u00e9tranger\",\"author\":[{\"@type\":\"Person\",\"name\":\"TransferGo Team\"}],\"creator\":[\"TransferGo Team\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"TransferGo\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-28T23:36:37Z\",\"datePublished\":\"2024-07-28T23:36:37Z\",\"dateModified\":\"2025-01-08T16:46:16Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/transfergo.com\/p.js"},"jetpack_featured_media_url":"https:\/\/www.transfergo.com\/wp-content\/uploads\/2024\/08\/iStock-1474998532.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.transfergo.com\/fr\/wp-json\/wp\/v2\/posts\/59039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.transfergo.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.transfergo.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.transfergo.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.transfergo.com\/fr\/wp-json\/wp\/v2\/comments?post=59039"}],"version-history":[{"count":1,"href":"https:\/\/www.transfergo.com\/fr\/wp-json\/wp\/v2\/posts\/59039\/revisions"}],"predecessor-version":[{"id":102127,"href":"https:\/\/www.transfergo.com\/fr\/wp-json\/wp\/v2\/posts\/59039\/revisions\/102127"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.transfergo.com\/fr\/wp-json\/wp\/v2\/media\/75252"}],"wp:attachment":[{"href":"https:\/\/www.transfergo.com\/fr\/wp-json\/wp\/v2\/media?parent=59039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.transfergo.com\/fr\/wp-json\/wp\/v2\/categories?post=59039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.transfergo.com\/fr\/wp-json\/wp\/v2\/tags?post=59039"},{"taxonomy":"business_case_studies_tags","embeddable":true,"href":"https:\/\/www.transfergo.com\/fr\/wp-json\/wp\/v2\/business_case_studies_tags?post=59039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}